{"id":499,"date":"2023-02-23T19:19:31","date_gmt":"2023-02-23T18:19:31","guid":{"rendered":"http:\/\/www.radio-gehacktes.de\/?p=499"},"modified":"2023-02-23T19:19:31","modified_gmt":"2023-02-23T18:19:31","slug":"uwe-machts","status":"publish","type":"post","link":"http:\/\/www.radio-gehacktes.de\/index.php\/2023\/02\/23\/uwe-machts\/","title":{"rendered":"Uwe macht&#8217;s"},"content":{"rendered":"\n<p>Zack! Ist schon wieder Donnerstag und um 21.00 Uhr ist es Zeit f\u00fcr Radio Gehacktes!<\/p>\n\n\n\n<p>Der Czelle macht Nachtschicht, der Paul Sp\u00e4tschicht, der Micha ist mit seiner Holden in Hamburg und das bedeutet: es ist nur der &#8222;Metal-Papa&#8220; Uwe \u00fcbrig. Lasst uns also hoffen, das der alte Mann seine Zipperlein in den Griff bekommt und alleine seinen Rollator ins Dachgeschoss des Sendeturmes wuchten kann. Und dann hat er hoffentlich auch noch die Puste f\u00fcr die eine oder Ansage&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zack! Ist schon wieder Donnerstag und um 21.00 Uhr ist es Zeit f\u00fcr Radio Gehacktes! Der Czelle macht Nachtschicht, der Paul Sp\u00e4tschicht, der Micha ist mit seiner Holden in Hamburg und das bedeutet: es ist nur der &#8222;Metal-Papa&#8220; Uwe \u00fcbrig. Lasst uns also hoffen, das der alte Mann seine Zipperlein in den Griff bekommt und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,5],"tags":[],"class_list":["post-499","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-termine"],"_links":{"self":[{"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/posts\/499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":1,"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/posts\/499\/revisions"}],"predecessor-version":[{"id":500,"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/posts\/499\/revisions\/500"}],"wp:attachment":[{"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/media?parent=499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/categories?post=499"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radio-gehacktes.de\/index.php\/wp-json\/wp\/v2\/tags?post=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}